{"id":1072,"count":1,"description":"","link":"https:\/\/odesa.one\/ru\/tag\/krazha-kvartiry","name":"\u043a\u0440\u0430\u0436\u0430 \u043a\u0432\u0430\u0440\u0442\u0438\u0440\u044b","slug":"krazha-kvartiry","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/odesa.one\/ru\/wp-json\/wp\/v2\/tags\/1072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/odesa.one\/ru\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/odesa.one\/ru\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/odesa.one\/ru\/wp-json\/wp\/v2\/posts?tags=1072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}