{"id":10996,"count":1,"description":"","link":"https:\/\/odesa.one\/ru\/tag\/narodnoe-uchilishhe-i-gimnaziya-dlya-devochek","name":"\u043d\u0430\u0440\u043e\u0434\u043d\u043e\u0435 \u0443\u0447\u0438\u043b\u0438\u0449\u0435 \u0438 \u0433\u0438\u043c\u043d\u0430\u0437\u0438\u044f \u0434\u043b\u044f \u0434\u0435\u0432\u043e\u0447\u0435\u043a","slug":"narodnoe-uchilishhe-i-gimnaziya-dlya-devochek","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/odesa.one\/ru\/wp-json\/wp\/v2\/tags\/10996","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/odesa.one\/ru\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/odesa.one\/ru\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/odesa.one\/ru\/wp-json\/wp\/v2\/posts?tags=10996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}