{"id":11063,"count":1,"description":"","link":"https:\/\/odesa.one\/ru\/tag\/odesskij-universitet-imeni-mechnikova","name":"\u041e\u0434\u0435\u0441\u0441\u043a\u0438\u0439 \u0443\u043d\u0438\u0432\u0435\u0440\u0441\u0438\u0442\u0435\u0442 \u0438\u043c\u0435\u043d\u0438 \u041c\u0435\u0447\u043d\u0438\u043a\u043e\u0432\u0430","slug":"odesskij-universitet-imeni-mechnikova","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/odesa.one\/ru\/wp-json\/wp\/v2\/tags\/11063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/odesa.one\/ru\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/odesa.one\/ru\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/odesa.one\/ru\/wp-json\/wp\/v2\/posts?tags=11063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}