{"id":11064,"count":1,"description":"","link":"https:\/\/odesa.one\/ru\/tag\/prohodivshie-cherez-zhiznennye-buri","name":"\u043f\u0440\u043e\u0445\u043e\u0434\u0438\u0432\u0448\u0438\u0435 \u0447\u0435\u0440\u0435\u0437 \u0436\u0438\u0437\u043d\u0435\u043d\u043d\u044b\u0435 \u0431\u0443\u0440\u0438","slug":"prohodivshie-cherez-zhiznennye-buri","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/odesa.one\/ru\/wp-json\/wp\/v2\/tags\/11064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/odesa.one\/ru\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/odesa.one\/ru\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/odesa.one\/ru\/wp-json\/wp\/v2\/posts?tags=11064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}