{"id":1698,"count":10,"description":"","link":"https:\/\/odesa.one\/ru\/tag\/ucheniki-v-odesse","name":"\u0443\u0447\u0435\u043d\u0438\u043a\u0438 \u0432 \u043e\u0434\u0435\u0441\u0441\u0435","slug":"ucheniki-v-odesse","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/odesa.one\/ru\/wp-json\/wp\/v2\/tags\/1698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/odesa.one\/ru\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/odesa.one\/ru\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/odesa.one\/ru\/wp-json\/wp\/v2\/posts?tags=1698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}