{"id":2247,"count":1,"description":"","link":"https:\/\/odesa.one\/ru\/tag\/uchet-deneg","name":"\u0443\u0447\u0435\u0442 \u0434\u0435\u043d\u0435\u0433","slug":"uchet-deneg","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/odesa.one\/ru\/wp-json\/wp\/v2\/tags\/2247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/odesa.one\/ru\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/odesa.one\/ru\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/odesa.one\/ru\/wp-json\/wp\/v2\/posts?tags=2247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}