{"id":3159,"count":0,"description":"","link":"https:\/\/odesa.one\/ru\/tag\/rozkopky-v-odesi-ru","name":"\u0440\u043e\u0437\u043a\u043e\u043f\u043a\u0438 \u0432 \u043e\u0434\u0435\u0441\u0456","slug":"rozkopky-v-odesi-ru","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/odesa.one\/ru\/wp-json\/wp\/v2\/tags\/3159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/odesa.one\/ru\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/odesa.one\/ru\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/odesa.one\/ru\/wp-json\/wp\/v2\/posts?tags=3159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}