{"id":5770,"count":1,"description":"","link":"https:\/\/odesa.one\/ru\/tag\/bezdomnye-istoriya","name":"\u0431\u0435\u0437\u0434\u043e\u043c\u043d\u044b\u0435 \u0438\u0441\u0442\u043e\u0440\u0438\u044f","slug":"bezdomnye-istoriya","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/odesa.one\/ru\/wp-json\/wp\/v2\/tags\/5770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/odesa.one\/ru\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/odesa.one\/ru\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/odesa.one\/ru\/wp-json\/wp\/v2\/posts?tags=5770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}