{"id":412,"count":2,"description":"","link":"https:\/\/odesa.one\/uk\/ukaz-moz-v-dele-ob-us%D1%8Bnovlenyy","name":"\u0443\u043a\u0430\u0437 \u041c\u041e\u0417 \u0432 \u0434\u0435\u043b\u0435 \u043e\u0431 \u0443\u0441\u044b\u043d\u043e\u0432\u043b\u0435\u043d\u0438\u0438","slug":"ukaz-moz-v-dele-ob-us%d1%8bnovlenyy","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/odesa.one\/uk\/wp-json\/wp\/v2\/tags\/412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/odesa.one\/uk\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/odesa.one\/uk\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/odesa.one\/uk\/wp-json\/wp\/v2\/posts?tags=412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}