{"id":9177,"count":1,"description":"","link":"https:\/\/odesa.one\/uk\/tag\/%d0%bf%d1%80%d0%be-%d0%bd%d0%b0%d0%b2%d1%87%d0%b0%d0%bb%d1%8c%d0%bd%d0%b8%d0%b9-%d0%bf%d1%80%d0%be%d1%86%d0%b5%d1%81-%d1%82%d0%b0-%d0%b1%d0%be%d0%bc%d0%b1%d0%be%d1%81%d1%85%d0%be%d0%b2%d0%b8%d1%89","name":"\u041f\u0440\u043e \u043d\u0430\u0432\u0447\u0430\u043b\u044c\u043d\u0438\u0439 \u043f\u0440\u043e\u0446\u0435\u0441 \u0442\u0430 \u0431\u043e\u043c\u0431\u043e\u0441\u0445\u043e\u0432\u0438\u0449\u0430","slug":"%d0%bf%d1%80%d0%be-%d0%bd%d0%b0%d0%b2%d1%87%d0%b0%d0%bb%d1%8c%d0%bd%d0%b8%d0%b9-%d0%bf%d1%80%d0%be%d1%86%d0%b5%d1%81-%d1%82%d0%b0-%d0%b1%d0%be%d0%bc%d0%b1%d0%be%d1%81%d1%85%d0%be%d0%b2%d0%b8%d1%89","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/odesa.one\/uk\/wp-json\/wp\/v2\/tags\/9177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/odesa.one\/uk\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/odesa.one\/uk\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/odesa.one\/uk\/wp-json\/wp\/v2\/posts?tags=9177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}